{"id":18,"date":"2025-06-23T18:47:05","date_gmt":"2025-06-23T16:47:05","guid":{"rendered":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/?p=18"},"modified":"2026-02-17T13:53:56","modified_gmt":"2026-02-17T12:53:56","slug":"illustrations","status":"publish","type":"post","link":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/2025\/06\/23\/illustrations\/","title":{"rendered":"Galerie d&rsquo;illustrations"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group alignwide has-base-background-color has-background is-layout-grid wp-container-core-group-is-layout-840b37f5 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-large wp-container-content-7ed1b8cc\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"878\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/nami-pastel-medium-1-1024x878.jpg\" alt=\"\" class=\"wp-image-11\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/nami-pastel-medium-1-1024x878.jpg 1024w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/nami-pastel-medium-1-300x257.jpg 300w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/nami-pastel-medium-1-768x658.jpg 768w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/nami-pastel-medium-1-1536x1317.jpg 1536w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/nami-pastel-medium-1-2048x1756.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2194\" height=\"2560\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1810-scaled.jpeg\" alt=\"\" class=\"wp-image-25\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1810-scaled.jpeg 2194w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1810-257x300.jpeg 257w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1810-878x1024.jpeg 878w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1810-768x896.jpeg 768w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1810-1317x1536.jpeg 1317w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1810-1755x2048.jpeg 1755w\" sizes=\"auto, (max-width: 2194px) 100vw, 2194px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"837\" height=\"768\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/a766c5d9-49f1-48a9-9fbd-e416091ae87f.jpg\" alt=\"\" class=\"wp-image-26\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/a766c5d9-49f1-48a9-9fbd-e416091ae87f.jpg 837w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/a766c5d9-49f1-48a9-9fbd-e416091ae87f-300x275.jpg 300w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/a766c5d9-49f1-48a9-9fbd-e416091ae87f-768x705.jpg 768w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2100\" height=\"2100\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044.png\" alt=\"\" class=\"wp-image-30\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044.png 2100w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044-300x300.png 300w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044-1024x1024.png 1024w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044-150x150.png 150w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044-768x768.png 768w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044-1536x1536.png 1536w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/Sans-titre-7_20240211210044-2048x2048.png 2048w\" sizes=\"auto, (max-width: 2100px) 100vw, 2100px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full wp-container-content-7ed1b8cc\"><img loading=\"lazy\" decoding=\"async\" width=\"1491\" height=\"1491\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_2023.jpeg\" alt=\"\" class=\"wp-image-24\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_2023.jpeg 1491w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_2023-300x300.jpeg 300w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_2023-1024x1024.jpeg 1024w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_2023-150x150.jpeg 150w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_2023-768x768.jpeg 768w\" sizes=\"auto, (max-width: 1491px) 100vw, 1491px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full wp-container-content-7ed1b8cc\"><img loading=\"lazy\" decoding=\"async\" width=\"1311\" height=\"1311\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/zelink.jpg\" alt=\"\" class=\"wp-image-22\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/zelink.jpg 1311w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/zelink-300x300.jpg 300w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/zelink-1024x1024.jpg 1024w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/zelink-150x150.jpg 150w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/zelink-768x768.jpg 768w\" sizes=\"auto, (max-width: 1311px) 100vw, 1311px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2194\" height=\"2560\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/pastel-luffyyy-scaled.png\" alt=\"\" class=\"wp-image-32\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/pastel-luffyyy-scaled.png 2194w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/pastel-luffyyy-257x300.png 257w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/pastel-luffyyy-878x1024.png 878w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/pastel-luffyyy-768x896.png 768w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/pastel-luffyyy-1317x1536.png 1317w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/pastel-luffyyy-1755x2048.png 1755w\" sizes=\"auto, (max-width: 2194px) 100vw, 2194px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2194\" height=\"2560\" src=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1491-scaled.jpeg\" alt=\"\" class=\"wp-image-27\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1491-scaled.jpeg 2194w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1491-257x300.jpeg 257w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1491-878x1024.jpeg 878w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1491-768x896.jpeg 768w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1491-1317x1536.jpeg 1317w, https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-content\/uploads\/2025\/06\/IMG_1491-1755x2048.jpeg 1755w\" sizes=\"auto, (max-width: 2194px) 100vw, 2194px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":10,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/posts\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":17,"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/posts\/18\/revisions"}],"predecessor-version":[{"id":119,"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/posts\/18\/revisions\/119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/media\/10"}],"wp:attachment":[{"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/media?parent=18"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/categories?post=18"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dnmade-sepr.fr\/2326\/lucie\/portfolio\/wp-json\/wp\/v2\/tags?post=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}